{"id":4254,"date":"2020-03-06T21:36:41","date_gmt":"2020-03-06T20:36:41","guid":{"rendered":"https:\/\/woffu.com\/?page_id=4254"},"modified":"2025-07-30T23:57:20","modified_gmt":"2025-07-30T21:57:20","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/woffu.com\/es\/terminos-y-condiciones\/","title":{"rendered":"T\u00e9rminos y condiciones"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<strong>CONDICIONES GENERALES<\/strong><\/p>\n<p>www.woffu.com<\/p>\n<p><strong>OBJETO Y ACEPTACI\u00d3N<\/strong><\/p>\n<p>Las presentes Condiciones Generales regulan la adquisici\u00f3n de los servicios ofertados en el sitio web www.woffu.com, del que es titular WOFFU JOB ORGANIZER SL (en adelante, WOFFU).<\/p>\n<p>La adquisici\u00f3n de cualesquiera de los servicios conlleva la aceptaci\u00f3n plena y sin reservas de todas y cada una de las Condiciones Generales que se indican, sin perjuicio de la aceptaci\u00f3n de las Condiciones Particulares que pudieran ser de aplicaci\u00f3n al adquirir determinados servicios.<\/p>\n<p>Estas Condiciones Generales podr\u00e1n ser modificadas sin notificaci\u00f3n previa, por tanto, es recomendable leer atentamente su contenido antes de proceder a la adquisici\u00f3n de cualquiera de los servicios ofertados.<\/p>\n<p><strong>IDENTIFICACI\u00d3N<\/strong><\/p>\n<p>Por una parte, WOFFU, en cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, le informa de que:<\/p>\n<p>Su denominaci\u00f3n social es: WOFFU JOB ORGANIZER SL.<\/p>\n<p>Su nombre comercial es: WOFFU.<\/p>\n<p>Su CIF es: B66473869.<\/p>\n<p>Su domicilio social est\u00e1 en: Carrer M\u00e9xic 8, 08004, Barcelona.<\/p>\n<p>Inscrita en el Registro Mercantil de BARCELONA Tomo 44681, Folio 188, Hoja 463366.<\/p>\n<p>Y, de otra parte, el Cliente.<\/p>\n<p>Ambas partes se reconocen mutuamente la capacidad legal para contratar y obligarse en las respectivas calidades en que act\u00faan y, en virtud del presente Contrato (como definido en los T\u00e9rminos Comerciales), acuerdan las siguientes Condiciones del Servicio.<\/p>\n<p><strong>COMUNICACIONES<\/strong><\/p>\n<p>Para comunicarse con nosotros, ponemos a su disposici\u00f3n diferentes medios de contacto que detallamos a continuaci\u00f3n:<\/p>\n<p>Tel\u00e9fono: 932 059 750<\/p>\n<p>Email: help@woffu.com<\/p>\n<p>Todas las notificaciones y comunicaciones entre los usuarios y WOFFU se considerar\u00e1n eficaces, a todos los efectos, cuando se realicen a trav\u00e9s de cualquier medio de los detallados anteriormente.<\/p>\n<p><strong>SERVICIOS<\/strong><\/p>\n<p>Los servicios ofertados, junto con las caracter\u00edsticas principales de los mismos se detallan en el apartado de precios en https:\/\/woffu.com\/precios-woffu\/<\/p>\n<p>WOFFU se reserva el derecho de decidir, en cada momento, los productos y\/o servicios que se ofrecen a los Clientes. De este modo, WOFFU podr\u00e1, en cualquier momento, a\u00f1adir nuevos productos y\/o servicios a los ofertados actualmente. Asimismo, WOFFU se reserva el derecho a retirar o dejar de ofrecer, en cualquier momento, y sin previo aviso, cualesquiera de los servicios ofrecidos.<\/p>\n<p>Todo ello sin perjuicio de que la adquisici\u00f3n de alguno de los servicios s\u00f3lo podr\u00e1 hacerse mediante la suscripci\u00f3n o registro del USUARIO, otorgando por parte de WOFFU al interesado un nombre de Usuario y una contrase\u00f1a, los cuales le identificar\u00e1n y habilitar\u00e1n personalmente para poder tener acceso a los servicios.<\/p>\n<p>Una vez dentro de www.woffu.com, y para acceder a la contrataci\u00f3n de los distintos servicios, el Usuario deber\u00e1 seguir todas las instrucciones indicadas en el proceso de compra, lo cual supondr\u00e1 la lectura y aceptaci\u00f3n de todas las condiciones generales y particulares fijadas en www.woffu.com.<\/p>\n<p><strong>PROCESO DE COMPRA Y\/O CONTRATACI\u00d3N<\/strong><\/p>\n<p>Para realizar cualquier compra en www.woffu.com, es necesario que el cliente sea mayor de edad.<\/p>\n<p>Adem\u00e1s, ser\u00e1 preciso que el cliente se registre en www.woffu.com a trav\u00e9s de un formulario de recogida de datos en el que se proporcione a WOFFU la informaci\u00f3n necesaria para la contrataci\u00f3n; datos que en cualquier caso ser\u00e1n veraces, exactos y completos sobre su identidad y que el cliente deber\u00e1 consentir expresamente mediante la aceptaci\u00f3n de la pol\u00edtica de privacidad de WOFFU.<\/p>\n<p>Los pasos a seguir para realizar la compra son:<\/p>\n<p>Registro usuario.<\/p>\n<p>Seleccionar producto.<\/p>\n<p>Seleccionar recurrencia de pago.<\/p>\n<p>Confirmaci\u00f3n de pedido.<\/p>\n<p>Asimismo, es recomendable que el cliente imprima y\/o guarde una copia en soporte duradero de las condiciones de venta al realizar su pedido, as\u00ed como tambi\u00e9n del comprobante de recepci\u00f3n enviado por WOFFU por correo electr\u00f3nico.<\/p>\n<p><strong>FACTURACI\u00d3N<\/strong><\/p>\n<p>A tal efecto, el cliente consiente que dicha factura se le remita en formato electr\u00f3nico. Podr\u00e1, en cualquier momento, revocar este consentimiento electr\u00f3nicamente para recibir la factura en papel.<\/p>\n<p><strong>DURACI\u00d3N, RENOVACI\u00d3N Y CANCELACI\u00d3N DEL CONTRATO<\/strong><\/p>\n<p>DURACI\u00d3N: 12 meses.<\/p>\n<p>RENOVACI\u00d3N: Autom\u00e1tica.<\/p>\n<p>CANCELACI\u00d3N: 30 d\u00edas antes de la fecha de renovaci\u00f3n.<\/p>\n<p><strong>CONDICIONES ADICIONALES DE CONTRATACI\u00d3N<\/strong><\/p>\n<p>Precio y duraci\u00f3n<\/p>\n<p>El Cliente se obliga a satisfacer puntualmente todos los pagos debidos en virtud de lo establecido en este contrato. En caso de incumplimiento por el Cliente de los plazos de pago establecidos, Woffu podr\u00e1, transcurridos siete d\u00edas h\u00e1biles desde el vencimiento del plazo, suspender el servicio y considerar resuelto de pleno derecho el presente contrato, siendo exigible el importe de los servicios efectivamente prestados.<\/p>\n<p>El importe del servicio se actualizar\u00e1, anualmente, aplicando el IPC correspondiente salvo negociaci\u00f3n de periodos de contrataci\u00f3n m\u00e1s prolongados que se aplicar\u00e1 lo que se acuerde.<\/p>\n<p>En caso que, por circunstancias espec\u00edficas, a t\u00edtulo enunciativo y no limitativo, se produjeran, modificaciones o evoluciones de los servicios prestados a trav\u00e9s de la plataforma, aumento significativo del tr\u00e1fico correspondiente al Cliente, cambios normativos, etc.., podr\u00e1 revisarse, al alza, el importe del servicio.<\/p>\n<p>En caso de producirse el mencionado aumento, \u00e9ste se comunicar\u00e1 al Cliente, con justificaci\u00f3n del aumento operado y con una antelaci\u00f3n de 30 d\u00edas a la fecha de vencimiento del contrato. Si una vez recibida la comunicaci\u00f3n, el Cliente decidiera no continuar adherido a la plataforma podr\u00e1 proceder a su baja, sin penalizaci\u00f3n de ning\u00fan tipo.<\/p>\n<p><strong>Disponibilidad del servicio<\/strong><\/p>\n<p>El servicio contratado por el Cliente estar\u00e1 disponible las 24 horas del d\u00eda los 365 d\u00edas del a\u00f1o, y espec\u00edficamente durante Horarios Laborales Europeos, de las 08.00 a las 20.00, hora de Europa del Oeste.<\/p>\n<p>No obstante, el servicio puede verse interrumpido de forma temporal por cuestiones relativas a mantenimiento, evoluci\u00f3n o modificaci\u00f3n de la plataforma y similares (\u201cMantenimiento Programado\u201d), e incidencias t\u00e9cnicas (\u201cDowntime\u201d).<\/p>\n<p>Woffu se compromete a preavisar en su portal o de otra forma con al menos 24 horas de antelaci\u00f3n las interrupciones que sean debidas a circunstancias previsibles, tales como el mantenimiento y cortes de conectividad avisados por las compa\u00f1\u00edas. En tal caso, Woffu utilizar\u00e1 sus mejores esfuerzos para ejecutar el mantenimiento programado fuera de los Horarios Laborales Europeos.<\/p>\n<p>Woffu se compromete a solventar las incidencias o reparar el servicio contratado en el menor tiempo posible y a notificar al Cliente el posible retraso en el restablecimiento del servicio.<\/p>\n<p>Disponibilidad: La disponibilidad del servicio corresponde al porcentaje de tiempo en que el producto sea disponible para usuarios. Se mide durante meses naturales.<\/p>\n<p><strong>Terminaci\u00f3n<\/strong><\/p>\n<p>El contrato finalizar\u00e1, aparte de por las causas generales del Derecho, en los siguientes casos:<\/p>\n<ol>\n<li>a) Finalizaci\u00f3n del periodo inicial de duraci\u00f3n o de sus pr\u00f3rrogas.<\/li>\n<li>b) Resoluci\u00f3n por incumplimiento de alguna de las partes de las obligaciones derivadas del contrato.<\/li>\n<\/ol>\n<p>La terminaci\u00f3n del contrato por estas u otras causas no exime a las partes de cumplir con aquellas obligaciones que hubiere adquirido.<\/p>\n<p><strong>Disponibilidad del soporte<\/strong><\/p>\n<p>El soporte t\u00e9cnico al cliente se proporciona como parte de nuestros Customer Success Packages.<\/p>\n<p>Todo el soporte t\u00e9cnico se realiza durante el horario siguiente: Lunes a Jueves: 8.30-19 h y Viernes: 8.30-14:30 horas (hora de Europa del Oeste).<\/p>\n<p>Las preguntas relacionadas con el soporte t\u00e9cnico y las consultas de soporte se pueden enviar por correo electr\u00f3nico a help@woffu.com, directamente en el chat a trav\u00e9s de la plataforma Woffu o por tel\u00e9fono.<\/p>\n<p><strong>Confidencialidad y no divulgaci\u00f3n<\/strong><\/p>\n<p>El Servicio Woffu, que incluye las ideas y conceptos contenidos en \u00e9l y la documentaci\u00f3n que acompa\u00f1a al Servicio Woffu, incluyendo el Contrato, constituye nuestra informaci\u00f3n confidencial. No deber\u00e1 divulgar los detalles del Servicio Woffu, o parte del mismo, a ning\u00fan tercero.<\/p>\n<p>Esta secci\u00f3n sobrevivir\u00e1 a la terminaci\u00f3n de este acuerdo hasta y en la medida en que dicha informaci\u00f3n se haga p\u00fablica (excepto por el incumplimiento de estas obligaciones).<\/p>\n<p><strong>Requisitos t\u00e9cnicos<\/strong><\/p>\n<p>Woffu es una aplicaci\u00f3n web por lo que es imprescindible la conexi\u00f3n a la red para ordenadores de sobremesa o port\u00e1tiles.<\/p>\n<p>Woffu es compatible con los navegadores: Chrome 84 o superior, Firefox 79 o superior, Safari 12, Edge 80 o superior, Microsoft Internet Explorer no es compatible.<\/p>\n<p>App M\u00f3vil Woffu es compatible con los sistemas IOS 11.0 o superior y Android 5.0 o superior<\/p>\n<p><strong>Seguridad<\/strong><\/p>\n<p>La gesti\u00f3n del entorno de producci\u00f3n de Woffu se aloja en el cloud de Microsoft Azure (https:\/\/docs.microsoft.com\/en-us\/azure\/security\/azure-security), con una arquitectura Multitenancy que garantiza los requisitos necesarios para mantener un sistema de gesti\u00f3n de la seguridad de la informaci\u00f3n. La comunicaci\u00f3n entre el navegador y Woffu est\u00e1 asegurada con 256 bits Secure Socket Layer (SSL AES-256, claves de 256 bits). Todas las conexiones est\u00e1n protegidas mediante autenticaci\u00f3n y autorizaci\u00f3n. Todas las operaciones de los usuarios se registran junto con sus direcciones IP y otros complementos de la sesi\u00f3n.<\/p>\n<p>Woffu asegura por contrato la recuperaci\u00f3n efectiva de todos los datos e informaci\u00f3n de la empresa.<\/p>\n<p><strong>ENTREGA\u00a0<\/strong><\/p>\n<p>SERVICIOS<\/p>\n<p>La prestaci\u00f3n del servicio se va a realizar de la siguiente manera:<\/p>\n<p>Electr\u00f3nicamente.<\/p>\n<p><strong>FORMAS Y PLAZOS DE ENTREGA<\/strong><\/p>\n<p>Inmediato<\/p>\n<p>PRECIOS, GASTOS E IMPUESTOS<\/p>\n<p>Los precios de los servicios que se recogen en www.woffu.com vendr\u00e1n expresados en Euros salvo que se exprese lo contrario y estar\u00e1n garantizados durante el tiempo de validez de los mismos, salvo error de impresi\u00f3n y sea cual sea el destino del pedido.<\/p>\n<p><strong>SERVICIOS<\/strong><\/p>\n<p>Los precios finales de todos los servicios, junto a sus caracter\u00edsticas, las ofertas, descuentos, etc. se reflejan en cada uno de los servicios que se ofrecen en <a href=\"https:\/\/woffu.com\/es\/\">www.woffu.com<\/a>.<\/p>\n<p>Los servicios contratados, junto con las caracter\u00edsticas principales de los mismos se detallan en el apartado de precios en https:\/\/woffu.com\/precios-woffu\/<\/p>\n<p>Los servicios no tienen el IVA incluido.<\/p>\n<p>El tipo de IVA es seg\u00fan el pa\u00eds de la UE.<\/p>\n<p>Los precios de los servicios pueden variar en cualquier momento. En este caso, el precio a aplicar ser\u00e1 el vigente en la fecha de realizaci\u00f3n del pedido. De cualquier modo, el coste final ser\u00e1 comunicado al cliente en el proceso de compra electr\u00f3nica antes de que \u00e9ste formalice su aceptaci\u00f3n.<\/p>\n<p><strong>FORMAS DE PAGO<\/strong><\/p>\n<p>Ponemos a su disposici\u00f3n estas formas de pago:<\/p>\n<p>Por tarjeta de cr\u00e9dito o d\u00e9bito<\/p>\n<p>Puede realizar el pago de manera inmediata a trav\u00e9s de la pasarela de pago seguro SSL de nuestro Banco. Si fuera necesario realizar cualquier devoluci\u00f3n o cancelaci\u00f3n del pedido, el importe se reembolsar\u00e1 a trav\u00e9s de la misma tarjeta de pago.\u00a0 Los datos tanto personales como bancarios estar\u00e1n protegidos con todas las medidas de seguridad establecidas por la Ley Org\u00e1nica 3\/2018, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales (LOPDGDD) y el Reglamento General de Protecci\u00f3n de Datos (RGPD) con total confidencialidad.<\/p>\n<p>Por Transferencia bancaria<\/p>\n<p>Mediante ingreso en efectivo o transferencia bancaria a favor de: Entidad: Caixabank. N\u00famero de cuenta: ES55 2100 0555 3502 0234 0252. Debiendo indicar en el momento de realizar la transferencia el nombre del cliente y n\u00famero de pedido.<\/p>\n<p>Mediante domiciliaci\u00f3n bancaria<\/p>\n<p>Debi\u00e9ndose indicar en la hoja de confirmaci\u00f3n de pedido su n\u00famero de cuenta corriente en la cual habr\u00e1 de cargarse el pedido.\u00a0 En caso de tener que realizar devoluciones de dinero, se abonar\u00e1 el importe directamente en su cuenta.<\/p>\n<p><strong>POL\u00cdTICA DE DEVOLUCIONES Y DESISTIMIENTO<\/strong><\/p>\n<p>Seg\u00fan establece la normativa, el consumidor y usuario tendr\u00e1 derecho a DESISTIR del contrato durante un per\u00edodo m\u00e1ximo de 14 d\u00edas naturales sin necesidad de indicar el motivo y sin incurrir en ning\u00fan coste, salvo los previstos en el art. 107.2 y 108 del RD1\/2007, de 16 de noviembre, por el que se aprueba el texto referido de la Ley General para la Defensa de los Consumidores y Usuarios.<\/p>\n<p>Este derecho de desistimiento no es aplicable entre otros a:<\/p>\n<p>Prestaci\u00f3n de servicios ya ejecutados o comenzados.<\/p>\n<p>Los contratos de suministro de grabaciones sonoras o de v\u00eddeo, de discos y de programas inform\u00e1ticos que hubiesen sido desprecintados por el consumidor y usuario, as\u00ed como de ficheros inform\u00e1ticos, suministrados por v\u00eda electr\u00f3nica, susceptibles de ser descargados o reproducidos con car\u00e1cter inmediato para su uso permanente.<\/p>\n<p><strong>SERVICIOS<\/strong><\/p>\n<p>El plazo para desistir del contrato de prestaci\u00f3n de servicios es de 14 d\u00edas naturales desde el d\u00eda de la celebraci\u00f3n del contrato, debiendo el usuario poner en conocimiento de WOFFU su deseo de ejercitar tal derecho, lo que podr\u00e1 hacer rellenando el formulario que se encuentra al final de este documento.<\/p>\n<p>El ejercicio del derecho de desistimiento da lugar a la suspensi\u00f3n del servicio.<\/p>\n<p>WOFFU comunicar\u00e1 al consumidor en soporte duradero un acuse de recibo de dicho desistimiento.<\/p>\n<p>El desistimiento implica que, WOFFU proceder\u00e1 a la devoluci\u00f3n del importe ya abonado por el cliente en un plazo m\u00e1ximo de 14 d\u00edas naturales, siguiendo el mismo procedimiento elegido por el cliente para su abono (siempre que el servicio contratado no est\u00e9 dentro de las excepciones indicadas anteriormente).<\/p>\n<p>Una vez recibamos su solicitud nos pondremos en contacto con el cliente para indicarle los detalles de la devoluci\u00f3n.<\/p>\n<p><strong>OBSERVACIONES<\/strong><\/p>\n<p>No aplica.<\/p>\n<p><strong>RESPONSABILIDAD Y EXONERACI\u00d3N DE RESPONSABILIDAD<\/strong><\/p>\n<p>WOFFU podr\u00e1 suspender, retirar o cancelar parcial o totalmente los servicios sometidos a contrataci\u00f3n en cualquier momento y sin necesidad de aviso previo. La previsi\u00f3n anterior no afectar\u00e1 a aquellos servicios que est\u00e1n reservados para usuarios registrados o que son objeto de contrataci\u00f3n previa y que se regir\u00e1n por sus condiciones espec\u00edficas (<a href=\"https:\/\/woffu.com\/es\/licencia-de-uso-del-software-woffu\/\">Licencia de uso<\/a>)<\/p>\n<p>La web puede contener v\u00ednculos o enlaces a otros sitios web y aplicaciones de terceros. WOFFU no se hace responsable de los sitios web y aplicaciones de terceros a los que se acceda a trav\u00e9s del sitio web, incluyendo la informaci\u00f3n contenida en los mismos.<\/p>\n<p><strong>ATENCI\u00d3N AL CLIENTE Y RECLAMACIONES<\/strong><\/p>\n<p>Para interponer cualquier queja o reclamaci\u00f3n ante WOFFU el cliente deber\u00e1 dirigirse al departamento de atenci\u00f3n al cliente bien en el n\u00famero de tel\u00e9fono 932059750, bien a trav\u00e9s de la direcci\u00f3n de correo electr\u00f3nico info@woffu.com.<\/p>\n<p>Seg\u00fan la Resoluci\u00f3n de litigios en l\u00ednea en materia de consumo de la UE y conforme al Art. 14.1 del Reglamento (UE) 524\/2013, le informamos que la Comisi\u00f3n Europea facilita a todos los consumidores una plataforma de resoluci\u00f3n de litigios en l\u00ednea que se encuentra disponible en el siguiente enlace: http:\/\/ec.europa.eu\/consumers\/odr\/.<\/p>\n<p><strong>USO DE LOGOS Y MARCAS<\/strong><\/p>\n<p>Woffu y el Cliente acuerdan el uso de sus respectivos logos y marcas durante la vigencia de la relaci\u00f3n comercial, conforme a los requisitos exigidos por la normativa aplicable.<\/p>\n<p>Este consentimiento podr\u00e1 ser revocado en cualquier momento mediante notificaci\u00f3n por escrito a la otra parte.<\/p>\n<p><strong>LEGISLACI\u00d3N APLICABLE<\/strong><\/p>\n<p>Las condiciones presentes se regir\u00e1n por la legislaci\u00f3n espa\u00f1ola vigente.<\/p>\n<p>La lengua utilizada ser\u00e1 el Castellano.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FORMULARIO DE DESESTIMIENTO <\/strong><\/p>\n<p>Asunto: Desistimiento del contrato<\/p>\n<p>En: __________________________ , a ____\/____\/____<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A la atenci\u00f3n de Woffu Job Organizer SL<\/p>\n<p>NIF B66473869<\/p>\n<p>Carrer M\u00e9xic 8, 08004, Barcelona<\/p>\n<p>+34 93 205 97 50<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por medio de la presente ponemos en su conocimiento nuestra voluntad de DESISTIR de nuestra suscripci\u00f3n a los siguientes servicios:<\/p>\n<p>&nbsp;<\/p>\n<p>Tipo de Servicio: _____Woffu Platform__________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p>Fecha de Suscripci\u00f3n: ________________________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p>Titular de la Suscripci\u00f3n: ______________________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p>Representante legal: _________________________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026.<\/p>\n<p>Firma Cliente<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El cliente tiene la opci\u00f3n de cumplimentar y enviar electr\u00f3nicamente este formulario de desistimiento o cualquier otra comunicaci\u00f3n inequ\u00edvoca al mail <a href=\"mailto:help@woffu.com\">help@woffu.com<\/a> dentro de los 14 d\u00edas naturales desde la celebraci\u00f3n del contrato de servicios.<\/p>\n<p><strong>\u00a0<\/strong>[\/vc_column_text][vc_raw_html]JTNDc3R5bGUlM0UlMEElMjNtYWluJTIwJTdCJTBBJTIwJTIwJTIwJTIwYmFja2dyb3VuZCUzQSUyMHdoaXRlJTNCJTBBJTdEJTBBJTNDJTJGc3R5bGUlM0U=[\/vc_raw_html][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]CONDICIONES GENERALES www.woffu.com OBJETO Y ACEPTACI\u00d3N Las presentes Condiciones Generales regulan la adquisici\u00f3n de los servicios ofertados en el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-new-legal.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-4254","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9rminos y condiciones | Woffu<\/title>\n<meta name=\"description\" content=\"Consulta los t\u00e9rminos y condiciones de Woffu, el software de control horario y recursos humanos que utilizan un gran n\u00famero de empresas cada d\u00eda\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9rminos y condiciones | Woffu\" \/>\n<meta property=\"og:description\" content=\"Consulta los t\u00e9rminos y condiciones de Woffu, el software de control horario y recursos humanos que utilizan un gran n\u00famero de empresas cada d\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/woffu.com\/es\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Woffu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/woffu\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T21:57:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/woffu.com\/wp-content\/uploads\/2025\/07\/woffu-logo-color-marketplace.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"625\" \/>\n\t<meta property=\"og:image:height\" content=\"332\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Woffu_App\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/woffu.com\\\/es\\\/terminos-y-condiciones\\\/\",\"url\":\"https:\\\/\\\/woffu.com\\\/es\\\/terminos-y-condiciones\\\/\",\"name\":\"T\u00e9rminos y condiciones | Woffu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/woffu.com\\\/es\\\/#website\"},\"datePublished\":\"2020-03-06T20:36:41+00:00\",\"dateModified\":\"2025-07-30T21:57:20+00:00\",\"description\":\"Consulta los t\u00e9rminos y condiciones de Woffu, el software de control horario y recursos humanos que utilizan un gran n\u00famero de empresas cada d\u00eda\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/woffu.com\\\/es\\\/terminos-y-condiciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/woffu.com\\\/es\\\/terminos-y-condiciones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/woffu.com\\\/es\\\/terminos-y-condiciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/woffu.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9rminos y condiciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/woffu.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/woffu.com\\\/es\\\/\",\"name\":\"Woffu\",\"description\":\"Woffu es una plataforma digital que facilita la gesti\u00f3n del tiempo laboral, control horario, vacaciones y ausencias, optimizando procesos de recursos humanos y asegurando el cumplimiento normativo en las empresas.\",\"publisher\":{\"@id\":\"https:\\\/\\\/woffu.com\\\/es\\\/#organization\"},\"alternateName\":\"Woffu\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/woffu.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/woffu.com\\\/es\\\/#organization\",\"name\":\"Woffu\",\"url\":\"https:\\\/\\\/woffu.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/woffu.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/woffu.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-woffu-dark.svg\",\"contentUrl\":\"https:\\\/\\\/woffu.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-woffu-dark.svg\",\"width\":161,\"height\":38,\"caption\":\"Woffu\"},\"image\":{\"@id\":\"https:\\\/\\\/woffu.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/woffu\\\/\",\"https:\\\/\\\/x.com\\\/Woffu_App\",\"https:\\\/\\\/www.instagram.com\\\/woffu\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/woffu\\\/\"],\"telephone\":\"+34 932059750\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Carrer de Mexic, 8\",\"postalCode\":\"08004\",\"addressLocality\":\"Barcelona\",\"addressCountry\":\"ES\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"customer support\",\"telephone\":\"+34 932059750\",\"email\":\"help@woffu.com\",\"url\":\"https:\\\/\\\/woffu.com\\\/es\\\/contacto\\\/\",\"areaServed\":\"ES\",\"availableLanguage\":[\"es\",\"en\"],\"hoursAvailable\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\"],\"opens\":\"08:30\",\"closes\":\"19:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":\"https:\\\/\\\/schema.org\\\/Friday\",\"opens\":\"08:30\",\"closes\":\"14:00\"}]},{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"telephone\":\"+34 932059750\",\"email\":\"sales@woffu.com\",\"url\":\"https:\\\/\\\/woffu.com\\\/es\\\/demo\\\/\",\"areaServed\":\"ES\",\"availableLanguage\":[\"es\",\"en\"],\"hoursAvailable\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"https:\\\/\\\/schema.org\\\/Monday\",\"https:\\\/\\\/schema.org\\\/Tuesday\",\"https:\\\/\\\/schema.org\\\/Wednesday\",\"https:\\\/\\\/schema.org\\\/Thursday\"],\"opens\":\"08:30\",\"closes\":\"19:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":\"https:\\\/\\\/schema.org\\\/Friday\",\"opens\":\"08:30\",\"closes\":\"14:00\"}]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos y condiciones | Woffu","description":"Consulta los t\u00e9rminos y condiciones de Woffu, el software de control horario y recursos humanos que utilizan un gran n\u00famero de empresas cada d\u00eda","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"T\u00e9rminos y condiciones | Woffu","og_description":"Consulta los t\u00e9rminos y condiciones de Woffu, el software de control horario y recursos humanos que utilizan un gran n\u00famero de empresas cada d\u00eda","og_url":"https:\/\/woffu.com\/es\/terminos-y-condiciones\/","og_site_name":"Woffu","article_publisher":"https:\/\/www.facebook.com\/woffu\/","article_modified_time":"2025-07-30T21:57:20+00:00","og_image":[{"width":625,"height":332,"url":"https:\/\/woffu.com\/wp-content\/uploads\/2025\/07\/woffu-logo-color-marketplace.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@Woffu_App","twitter_misc":{"Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/woffu.com\/es\/terminos-y-condiciones\/","url":"https:\/\/woffu.com\/es\/terminos-y-condiciones\/","name":"T\u00e9rminos y condiciones | Woffu","isPartOf":{"@id":"https:\/\/woffu.com\/es\/#website"},"datePublished":"2020-03-06T20:36:41+00:00","dateModified":"2025-07-30T21:57:20+00:00","description":"Consulta los t\u00e9rminos y condiciones de Woffu, el software de control horario y recursos humanos que utilizan un gran n\u00famero de empresas cada d\u00eda","breadcrumb":{"@id":"https:\/\/woffu.com\/es\/terminos-y-condiciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/woffu.com\/es\/terminos-y-condiciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/woffu.com\/es\/terminos-y-condiciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/woffu.com\/es\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos y condiciones"}]},{"@type":"WebSite","@id":"https:\/\/woffu.com\/es\/#website","url":"https:\/\/woffu.com\/es\/","name":"Woffu","description":"Woffu es una plataforma digital que facilita la gesti\u00f3n del tiempo laboral, control horario, vacaciones y ausencias, optimizando procesos de recursos humanos y asegurando el cumplimiento normativo en las empresas.","publisher":{"@id":"https:\/\/woffu.com\/es\/#organization"},"alternateName":"Woffu","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/woffu.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/woffu.com\/es\/#organization","name":"Woffu","url":"https:\/\/woffu.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/woffu.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/woffu.com\/wp-content\/uploads\/2021\/08\/logo-woffu-dark.svg","contentUrl":"https:\/\/woffu.com\/wp-content\/uploads\/2021\/08\/logo-woffu-dark.svg","width":161,"height":38,"caption":"Woffu"},"image":{"@id":"https:\/\/woffu.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/woffu\/","https:\/\/x.com\/Woffu_App","https:\/\/www.instagram.com\/woffu\/","https:\/\/www.linkedin.com\/company\/woffu\/"],"telephone":"+34 932059750","address":{"@type":"PostalAddress","streetAddress":"Carrer de Mexic, 8","postalCode":"08004","addressLocality":"Barcelona","addressCountry":"ES"},"contactPoint":[{"@type":"ContactPoint","contactType":"customer support","telephone":"+34 932059750","email":"help@woffu.com","url":"https:\/\/woffu.com\/es\/contacto\/","areaServed":"ES","availableLanguage":["es","en"],"hoursAvailable":[{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday"],"opens":"08:30","closes":"19:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":"https:\/\/schema.org\/Friday","opens":"08:30","closes":"14:00"}]},{"@type":"ContactPoint","contactType":"sales","telephone":"+34 932059750","email":"sales@woffu.com","url":"https:\/\/woffu.com\/es\/demo\/","areaServed":"ES","availableLanguage":["es","en"],"hoursAvailable":[{"@type":"OpeningHoursSpecification","dayOfWeek":["https:\/\/schema.org\/Monday","https:\/\/schema.org\/Tuesday","https:\/\/schema.org\/Wednesday","https:\/\/schema.org\/Thursday"],"opens":"08:30","closes":"19:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":"https:\/\/schema.org\/Friday","opens":"08:30","closes":"14:00"}]}]}]}},"_links":{"self":[{"href":"https:\/\/woffu.com\/es\/wp-json\/wp\/v2\/pages\/4254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/woffu.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/woffu.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/woffu.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/woffu.com\/es\/wp-json\/wp\/v2\/comments?post=4254"}],"version-history":[{"count":3,"href":"https:\/\/woffu.com\/es\/wp-json\/wp\/v2\/pages\/4254\/revisions"}],"predecessor-version":[{"id":11619,"href":"https:\/\/woffu.com\/es\/wp-json\/wp\/v2\/pages\/4254\/revisions\/11619"}],"wp:attachment":[{"href":"https:\/\/woffu.com\/es\/wp-json\/wp\/v2\/media?parent=4254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}